{"id":21254,"date":"2021-06-04T10:53:38","date_gmt":"2021-06-04T10:53:38","guid":{"rendered":"https:\/\/www.edgenexus.io\/ressourcen\/load-balancer-faq-und-terminologie\/"},"modified":"2022-07-07T14:44:15","modified_gmt":"2022-07-07T14:44:15","slug":"load-balancer-faq-und-terminologie","status":"publish","type":"page","link":"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/","title":{"rendered":"Load Balancer FAQ und Terminologie"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"21254\" class=\"elementor elementor-21254 elementor-17879\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa7c9fc elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"fa7c9fc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-38f9156\" data-id=\"38f9156\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1658c2 elementor-widget elementor-widget-heading\" data-id=\"d1658c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0baf6fc elementor-widget elementor-widget-heading\" data-id=\"0baf6fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Lassen Sie uns technisch werden<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39f527c elementor-widget elementor-widget-tp-button\" data-id=\"39f527c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pt-plus-button-wrapper   text- text--mobilecenter   \"><div class=\"button_parallax   \" ><div id=\"button6a04f0c51261b\"  class=\" text- text--mobilecenter ts-button content_hover_effect content_hover_float  \" ><div class=\"pt_plus_button btn6a04f0c5122f5 button-style-8   \"  ><div class=\"animted-content-inner \"><a href=\"https:\/\/www.edgenexus.io\/load-balancer\/free-trial\/\" target=\"_blank\" class=\"button-link-wrap \" role=\"button\" data-hover=\"Kostenlose Testversion herunterladen\"  >Kostenlose Testversion herunterladen<i class=\"btn-icon button-after fa fa-arrow-right\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6c2cd6b\" data-id=\"6c2cd6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8a1f02 elementor-widget elementor-widget-image\" data-id=\"e8a1f02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"492\" src=\"https:\/\/www.edgenexus.io\/wp-content\/uploads\/2021\/03\/edgenexus-tbd-faqAsset-1-768x492.png\" class=\"attachment-medium_large size-medium_large wp-image-35434\" alt=\"edgenexus tbd faq\" srcset=\"https:\/\/www.edgenexus.io\/wp-content\/uploads\/2021\/03\/edgenexus-tbd-faqAsset-1-768x492.png 768w, https:\/\/www.edgenexus.io\/wp-content\/uploads\/2021\/03\/edgenexus-tbd-faqAsset-1-400x256.png 400w, https:\/\/www.edgenexus.io\/wp-content\/uploads\/2021\/03\/edgenexus-tbd-faqAsset-1.png 1309w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5599deb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5599deb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-23d56d8\" data-id=\"23d56d8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b49362 elementor-position-inline-start web-chat elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8b49362\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.edgenexus.io\/de\/unterstuetzung\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"UNTERST\u00dcTZUNG\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"hm hm-support-call\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h6 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.edgenexus.io\/de\/unterstuetzung\/\" >\n\t\t\t\t\t\t\tUNTERST\u00dcTZUNG\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h6>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7fe8fba\" data-id=\"7fe8fba\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1222a3c elementor-position-inline-start web-chat elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1222a3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.edgenexus.io\/de\/products\/lastausgleicher\/kostenlose-testversion\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"KOSTENLOSES PROBLEM\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"hm hm-Download-circle\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h6 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.edgenexus.io\/de\/products\/lastausgleicher\/kostenlose-testversion\/\" >\n\t\t\t\t\t\t\tKOSTENLOSES PROBLEM\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h6>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-681fba0\" data-id=\"681fba0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfbba38 elementor-position-inline-start web-chat elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"bfbba38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.edgenexus.io\/contact\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"KONTAKT\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"hm hm-envelop2\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h6 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.edgenexus.io\/contact\/\" >\n\t\t\t\t\t\t\tKONTAKT\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h6>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30d01f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30d01f2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-adb4e3e\" data-id=\"adb4e3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3d28334 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d28334\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8c2bb63\" data-id=\"8c2bb63\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9ee321 elementor-widget elementor-widget-heading\" data-id=\"b9ee321\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Glossar und FAQ zur Terminologie des Lastausgleichs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eaee0b elementor-widget elementor-widget-heading\" data-id=\"6eaee0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Die Load-Balancing-Technologie hat sich in den letzten Jahren erheblich weiterentwickelt, so dass die Terminologie im Zusammenhang mit Application Delivery inzwischen recht verwirrend geworden ist. Angesichts der vielen Akronyme und des Fachjargons f\u00fchlt man sich leicht \u00fcberfordert, wenn man sich mit Lastverteilungsl\u00f6sungen besch\u00e4ftigt.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-011df3a elementor-icon-list--layout-traditional elementor-list-item-link-full_width ha-has-bg-overlay elementor-widget elementor-widget-icon-list\" data-id=\"011df3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bei Edgenexus halten wir die Dinge gerne einfach, deshalb haben wir einen n\u00fctzlichen Leitfaden zusammengestellt, der Ihnen zeigt, was Sie \u00fcber Load Balancing wissen m\u00fcssen und wie jede Funktion dem Benutzer n\u00fctzt.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-32c11eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32c11eb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-542d9ac\" data-id=\"542d9ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aae4959 ha-accordion--icon-left ha-has-bg-overlay elementor-widget elementor-widget-ha-accordion happy-addon ha-accordion happy-addon-pro\" data-id=\"aae4959\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ha-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"ha-accordion__wrapper\" role=\"tablist\">\n                            <div class=\"ha-accordion__item\">\n                    <div id=\"ha-accordion__item-title-1791\" class=\"ha-accordion__item-title\" data-tab=\"1\" role=\"tab\" aria-controls=\"ha-accordion__item-content-1791\">\n                                                    <span class=\"ha-accordion__item-icon ha-accordion__icon\" aria-hidden=\"true\">\n                                                                    <span class=\"ha-accordion__icon--closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n                                                                                                    <span class=\"ha-accordion__icon--opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n                                                            <\/span>\n                                                <div class=\"ha-accordion__item-title-inner\">\n                                                        <span class=\"ha-accordion__item-title-text\">Was ist ein Load Balancer?  <\/span>\n                        <\/div>\n                    <\/div>\n                    <div id=\"ha-accordion__item-content-1791\" class=\"ha-accordion__item-content\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"ha-accordion__item-title-1791\">\n                        <p>Ein Load Balancer ist eine Netzwerk-Appliance, die f\u00fcr die effektive Verteilung des eingehenden Netzwerkverkehrs auf mehrere Backend-Server verantwortlich ist, um stets verf\u00fcgbare Anwendungsdienste zu gew\u00e4hrleisten. Load Balancer k\u00f6nnen als Software-Appliances, Hardware-Appliances oder sogar als Service eingesetzt werden. Mit einem Load Balancer k\u00f6nnen Sie die Serverauslastung optimieren und Single Points of Failure bei der Anwendungsbereitstellung beseitigen, um Folgendes zu gew\u00e4hrleisten:  <\/p>\n<p><strong>Ausfallsicherheit<\/strong> &#8211; Ein Load Balancer erm\u00f6glicht es Ihnen, mehrere Anwendungsserver zu betreiben, die dieselbe Aufgabe erf\u00fcllen. Im Falle eines Serverausfalls erkennt der Load Balancer dies und leitet den Datenverkehr auf die verbleibenden, gesunden Online-Server um. Dies gew\u00e4hrleistet eine hohe Verf\u00fcgbarkeit und Zuverl\u00e4ssigkeit der Anwendungen.  <\/p>\n<p><strong>Skalierbarkeit<\/strong> &#8211; Load Balancer erm\u00f6glichen die nahtlose Skalierung von Diensten ohne Beeintr\u00e4chtigung der Leistung. Indem Sie einfach mehr Server hinter dem Load Balancer zur Verteilung hinzuf\u00fcgen, f\u00fchren Sie die F\u00e4higkeit ein, sich an einen Anstieg der Last anzupassen.  <\/p>\n<p><strong>Kapazit\u00e4t<\/strong> &#8211; Um die Kapazit\u00e4t zu erh\u00f6hen, f\u00fcgen Sie einfach weitere Server hinter dem Load Balancer hinzu. (Ok, so einfach ist es normalerweise nicht, da Sie wahrscheinlich Datenbanken und andere App-Server ber\u00fccksichtigen m\u00fcssen, aber Sie verstehen die Idee)<\/p><\/p>\n                    <\/div>\n                <\/div>\n                            <div class=\"ha-accordion__item\">\n                    <div id=\"ha-accordion__item-title-1792\" class=\"ha-accordion__item-title\" data-tab=\"2\" role=\"tab\" aria-controls=\"ha-accordion__item-content-1792\">\n                                                    <span class=\"ha-accordion__item-icon ha-accordion__icon\" aria-hidden=\"true\">\n                                                                    <span class=\"ha-accordion__icon--closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n                                                                                                    <span class=\"ha-accordion__icon--opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n                                                            <\/span>\n                                                <div class=\"ha-accordion__item-title-inner\">\n                                                        <span class=\"ha-accordion__item-title-text\">Wie funktioniert ein Load Balancer?<\/span>\n                        <\/div>\n                    <\/div>\n                    <div id=\"ha-accordion__item-content-1792\" class=\"ha-accordion__item-content\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"ha-accordion__item-title-1792\">\n                        <p>Load Balancer verteilen den Anwendungsverkehr basierend auf vielen verschiedenen <strong>Lastverteilungsstrategien<\/strong> oder <strong>Lastverteilungsrichtlinien<\/strong>, wie sie manchmal genannt werden. Um zu verstehen, ob ein Backend-Server online und gesund ist, verwendet ein Load Balancer die Backend-Server-\u00dcberwachung und die <strong>Server-Zustandspr\u00fcfung<\/strong>. Die Prinzipien des Lastausgleichs gibt es schon seit vielen Jahren, aber diese Ger\u00e4te haben sich erheblich weiterentwickelt, vom einfachen Layer4-Ger\u00e4t bis hin zu den viel anspruchsvolleren Layer7 Application Delivery Controllern, oder ADCs, wie Gartner sie nennt. ADCs bieten viele zus\u00e4tzliche wichtige Funktionen wie Sicherheit und Verkehrsmanagement.<\/p><\/p>\n                    <\/div>\n                <\/div>\n                            <div class=\"ha-accordion__item\">\n                    <div id=\"ha-accordion__item-title-1793\" class=\"ha-accordion__item-title\" data-tab=\"3\" role=\"tab\" aria-controls=\"ha-accordion__item-content-1793\">\n                                                    <span class=\"ha-accordion__item-icon ha-accordion__icon\" aria-hidden=\"true\">\n                                                                    <span class=\"ha-accordion__icon--closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n                                                                                                    <span class=\"ha-accordion__icon--opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n                                                            <\/span>\n                                                <div class=\"ha-accordion__item-title-inner\">\n                                                        <span class=\"ha-accordion__item-title-text\">  Was sind Load Balancing-Strategien und -Richtlinien?<\/span>\n                        <\/div>\n                    <\/div>\n                    <div id=\"ha-accordion__item-content-1793\" class=\"ha-accordion__item-content\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"ha-accordion__item-title-1793\">\n                        <p>Eine Lastausgleichsstrategie oder -richtlinie weist den Load Balancer an, wohin er die n\u00e4chste eingehende Anfrage senden soll. Es gibt viele Strategien f\u00fcr den Lastausgleich, die von der jeweiligen L\u00f6sung abh\u00e4ngen, aber ein paar g\u00e4ngige sind im Folgenden aufgef\u00fchrt:  <\/p>\n<p><strong>Round Robin<\/strong>: Die einfachste Methode der Lastverteilung, bei der jeder Server abwechselnd eine Anfrage erh\u00e4lt.  <\/p>\n<p><strong>Geringste Anzahl von Verbindungen<\/strong>: Der Load Balancer verfolgt die Anzahl der Verbindungen, die ein Server hat, und sendet die n\u00e4chste Anfrage an den Server mit den wenigsten Verbindungen.  <em>Hinweis<\/em>: \u00c4ltere, reine Layer4-Loadbalancer unterst\u00fctzen dies in der Regel nicht, da sie typischerweise DSR (Direct Server Return) ausf\u00fchren und nicht wissen, wie viele Verbindungen gerade auf den Backend-Servern liegen.  <\/p>\n<p><strong>Gewichtet<\/strong>: Typischerweise wird den Servern eine prozentuale F\u00e4higkeit zugewiesen, da ein Server doppelt so leistungsf\u00e4hig sein kann wie ein anderer. Gewichtete Methoden sind sinnvoll, wenn der Load Balancer die reale und tats\u00e4chliche Leistung des Servers nicht kennt.  <\/p>\n<p><strong>Schnellste Reaktionszeit<\/strong>: Diese Lastausgleichsmethode ist normalerweise nur bei fortschrittlicheren Produkten verf\u00fcgbar. Die Anfrage wird an den am schnellsten antwortenden Server gesendet.<\/p><\/p>\n                    <\/div>\n                <\/div>\n                            <div class=\"ha-accordion__item\">\n                    <div id=\"ha-accordion__item-title-1794\" class=\"ha-accordion__item-title\" data-tab=\"4\" role=\"tab\" aria-controls=\"ha-accordion__item-content-1794\">\n                                                    <span class=\"ha-accordion__item-icon ha-accordion__icon\" aria-hidden=\"true\">\n                                                                    <span class=\"ha-accordion__icon--closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n                                                                                                    <span class=\"ha-accordion__icon--opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n                                                            <\/span>\n                                                <div class=\"ha-accordion__item-title-inner\">\n                                                        <span class=\"ha-accordion__item-title-text\">  Was ist Server Health Checking?<\/span>\n                        <\/div>\n                    <\/div>\n                    <div id=\"ha-accordion__item-content-1794\" class=\"ha-accordion__item-content\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"ha-accordion__item-title-1794\">\n                        <p>Load Balancer f\u00fchren Server Health Checks gegen Webserver durch, um festzustellen, ob diese lebendig und gesund sind und Dienste anbieten. Die \u00dcberwachung des Serverzustands ist der Schl\u00fcssel zur Bereitstellung robuster Anwendungen, und je nach gew\u00e4hlter L\u00f6sung sind einige Load Balancer in der Lage, Layer7 Health Checks zu verwenden, die bei der Erkennung von Problemen eine gr\u00f6\u00dfere Raffinesse bieten. Im Folgenden finden Sie eine \u00dcbersicht \u00fcber die verschiedenen Methoden der Server-Zustandspr\u00fcfung.  <\/p>\n<p><strong>Ping<\/strong>: Dies ist die einfachste Methode zur \u00dcberpr\u00fcfung des Serverzustands, allerdings ist sie nicht sehr zuverl\u00e4ssig, da der Load Balancer melden kann, dass der Server in Betrieb ist, w\u00e4hrend der Webdienst immer noch ausgefallen sein kann.  <\/p>\n<p><strong>TCP-Verbindung<\/strong>: Dies ist eine anspruchsvollere Methode der Zustandspr\u00fcfung, mit der \u00fcberpr\u00fcft werden kann, ob ein Dienst aktiv ist und l\u00e4uft. Ein Beispiel hierf\u00fcr sind Dienste auf Port 80 f\u00fcr das Web.  <\/p>\n<p><strong>Einfacher HTTP-GET<\/strong>: Bei dieser Methode der Server-Zustandspr\u00fcfung wird eine HTTP-GET-Anfrage an den Webserver gestellt und typischerweise auf eine Header-Antwort, wie z. B. ein 200 OK, gepr\u00fcft.  <\/p>\n<p><strong>Vollst\u00e4ndiger HTTP-GET<\/strong>: Diese Server-Zustandspr\u00fcfung f\u00fchrt einen HTTP-GET aus und pr\u00fcft den eigentlichen Inhaltsk\u00f6rper auf eine korrekte Antwort. Diese Funktion ist nur bei einigen der fortschrittlicheren Lastausgleichsl\u00f6sungen verf\u00fcgbar, ist aber f\u00fcr Webanwendungen die \u00fcberlegene Methode, da sie pr\u00fcft, ob die tats\u00e4chliche Anwendung verf\u00fcgbar ist.  <\/p>\n<p><strong>Anpassbare Server Health Checks<\/strong>: Einige Load-Balancing-L\u00f6sungen sind in der Lage, benutzerdefinierte Monitore f\u00fcr TCP \/ IP-Anwendungen unterzubringen, um eine bessere Kontrolle \u00fcber ihre spezifischen Anwendungsdienste zu erm\u00f6glichen.<\/p><\/p>\n                    <\/div>\n                <\/div>\n                            <div class=\"ha-accordion__item\">\n                    <div id=\"ha-accordion__item-title-1795\" class=\"ha-accordion__item-title\" data-tab=\"5\" role=\"tab\" aria-controls=\"ha-accordion__item-content-1795\">\n                                                    <span class=\"ha-accordion__item-icon ha-accordion__icon\" aria-hidden=\"true\">\n                                                                    <span class=\"ha-accordion__icon--closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n                                                                                                    <span class=\"ha-accordion__icon--opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n                                                            <\/span>\n                                                <div class=\"ha-accordion__item-title-inner\">\n                                                        <span class=\"ha-accordion__item-title-text\">Was ist Persistenz und warum braucht man sie beim Server Load Balancing?<\/span>\n                        <\/div>\n                    <\/div>\n                    <div id=\"ha-accordion__item-content-1795\" class=\"ha-accordion__item-content\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"ha-accordion__item-title-1795\">\n                        <p>Persistenz ist eine Funktion, die von vielen Webanwendungen und Websites ben\u00f6tigt wird. Sobald ein Benutzer mit einem bestimmten Server interagiert hat, werden alle nachfolgenden Anfragen an denselben Server gesendet und bleiben somit auf diesem bestimmten Server &#8222;bestehen&#8220;. Die Sitzungspersistenz stellt die Kontinuit\u00e4t des Dienstes und eine nahtlose Endbenutzererfahrung sicher und ist oft eine Anforderung von E-Commerce-Anwendungen, deren Sitzungsstatus auf dem lokalen Webserver im Gegensatz zu einer gemeinsamen Datenbank gespeichert wird. Beharrlichkeit kann viele Formen annehmen&#8230;  <\/p>\n<p><strong>Load Balancer Cookie<\/strong>: Der Load Balancer setzt ein Cookie am Client und identifiziert damit den Backend-Server, der f\u00fcr diesen Benutzer verwendet werden soll.  <\/p>\n<p><strong>Anwendungssitzungs-Cookies<\/strong>: Viele Applikationsserver setzen bereits eine eigene Session-ID wie z. B. jsp session cookie oder Asp.net. Sie k\u00f6nnen den Load Balancer so konfigurieren, dass er diese verwendet.  <\/p>\n<p><strong>IP-basiert<\/strong>: Verwendet die Client-IP-Adresse zum Fortbestehen. Diese Methode funktioniert f\u00fcr Schicht4 und Schicht7.<\/p>\n<p><strong>SSL-Sitzung<\/strong>: Verwendet die SSL-Session-ID. Dies ist nicht sehr h\u00e4ufig, da sich die Sitzungs-ID \u00e4ndern kann und somit die Persistenz verloren geht.  <\/p>\n<p><strong>RDP-Sitzungs-Cookie<\/strong>: Wird f\u00fcr RDP-Verbindungen verwendet.<\/p><\/p>\n                    <\/div>\n                <\/div>\n                            <div class=\"ha-accordion__item\">\n                    <div id=\"ha-accordion__item-title-1796\" class=\"ha-accordion__item-title\" data-tab=\"6\" role=\"tab\" aria-controls=\"ha-accordion__item-content-1796\">\n                                                    <span class=\"ha-accordion__item-icon ha-accordion__icon\" aria-hidden=\"true\">\n                                                                    <span class=\"ha-accordion__icon--closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n                                                                                                    <span class=\"ha-accordion__icon--opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n                                                            <\/span>\n                                                <div class=\"ha-accordion__item-title-inner\">\n                                                        <span class=\"ha-accordion__item-title-text\">Was ist ein Application Delivery Controller (ADC)?<\/span>\n                        <\/div>\n                    <\/div>\n                    <div id=\"ha-accordion__item-content-1796\" class=\"ha-accordion__item-content\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"ha-accordion__item-title-1796\">\n                        <p>Dies ist ein Begriff, der zur Beschreibung eines fortschrittlichen Load Balancers verwendet wird. Nun sind die meisten Load Balancer Layer7-Appliances, die sich in einer privilegierten Position zwischen der Anwendung und den Clients befinden. Mit der Sichtbarkeit des gesamten Datenverkehrs kann der Load Balancer eine Reihe von Funktionen erf\u00fcllen, die \u00fcber den einfachen Lastausgleich und die Serverredundanz hinausgehen. Der Lastausgleich ist eine von mehreren Funktionen eines ADCs, darunter:<\/p>\n<ul>\n<li>Layer7-Verkehrsmanagement<\/li>\n<li>Beschleunigung der Anwendung<\/li>\n<li>Zwischenspeichern von Inhalten<\/li>\n<li>Anwendungs-Firewall<\/li>\n<li>Pooling und Begrenzung von Verbindungen<\/li>\n<li>Vorauthentifizierung und Single Sign-On<\/li>\n<li>Proxying<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n                            <div class=\"ha-accordion__item\">\n                    <div id=\"ha-accordion__item-title-1797\" class=\"ha-accordion__item-title\" data-tab=\"7\" role=\"tab\" aria-controls=\"ha-accordion__item-content-1797\">\n                                                    <span class=\"ha-accordion__item-icon ha-accordion__icon\" aria-hidden=\"true\">\n                                                                    <span class=\"ha-accordion__icon--closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n                                                                                                    <span class=\"ha-accordion__icon--opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n                                                            <\/span>\n                                                <div class=\"ha-accordion__item-title-inner\">\n                                                        <span class=\"ha-accordion__item-title-text\">  Was ist der Unterschied zwischen Layer4 und Layer7 Load Balancing?<\/span>\n                        <\/div>\n                    <\/div>\n                    <div id=\"ha-accordion__item-content-1797\" class=\"ha-accordion__item-content\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"ha-accordion__item-title-1797\">\n                        <p>Die Begriffe Layer4 und Layer7 bezeichnen die Protokollschichten, auf denen ein Load Balancer innerhalb des OSI-Netzwerkmodells arbeitet. Layer4-Load-Balancer arbeiten auf der Transportschicht, w\u00e4hrend Layer7-Load-Balancer auf der Ebene des Anwendungsprotokolls arbeiten, was ihnen eine bessere Sichtbarkeit und ein besseres Verst\u00e4ndnis der Anwendung, die sie selbst verarbeiten, erm\u00f6glicht. Dies erm\u00f6glicht erweiterte Funktionen und Optimierungsmerkmale wie intelligentes Traffic-Management, Content-Caching, Sicherheit und Komprimierung. <em>Beschleunigungsfunktionen<\/em> Layer4-Load-Balancer sind nach wie vor verf\u00fcgbar, obwohl ihr Marktanteil deutlich zur\u00fcckgegangen ist, da Layer7 Advanced Load Balancer und ADCs leistungsf\u00e4higer und kosteng\u00fcnstiger geworden sind.<\/p><\/p>\n                    <\/div>\n                <\/div>\n                            <div class=\"ha-accordion__item\">\n                    <div id=\"ha-accordion__item-title-1798\" class=\"ha-accordion__item-title\" data-tab=\"8\" role=\"tab\" aria-controls=\"ha-accordion__item-content-1798\">\n                                                    <span class=\"ha-accordion__item-icon ha-accordion__icon\" aria-hidden=\"true\">\n                                                                    <span class=\"ha-accordion__icon--closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n                                                                                                    <span class=\"ha-accordion__icon--opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n                                                            <\/span>\n                                                <div class=\"ha-accordion__item-title-inner\">\n                                                        <span class=\"ha-accordion__item-title-text\">Was ist SSL und HTTPS?<\/span>\n                        <\/div>\n                    <\/div>\n                    <div id=\"ha-accordion__item-content-1798\" class=\"ha-accordion__item-content\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"ha-accordion__item-title-1798\">\n                        <p>SSL (Secure Sockets Layer) beschreibt den Prozess der Verschl\u00fcsselung der Verbindung, typischerweise unter Verwendung eines privaten Zertifikats. HTTPS ist HTTP, das \u00fcber eine verschl\u00fcsselte SSL-Verbindung l\u00e4uft. SSL kann ein sehr CPU-intensiver Vorgang sein, der die Geschwindigkeit und Kapazit\u00e4t des Webservers reduziert. Das Auslagern der SSL-Terminierung an einen Load Balancer erm\u00f6glicht Ihnen die zentrale Verwaltung Ihrer Zertifikate und gibt Ihren Servern die M\u00f6glichkeit, sich auf die Bereitstellung der Anwendung zu konzentrieren, anstatt SSL zu entschl\u00fcsseln.<\/p><\/p>\n                    <\/div>\n                <\/div>\n                            <div class=\"ha-accordion__item\">\n                    <div id=\"ha-accordion__item-title-1799\" class=\"ha-accordion__item-title\" data-tab=\"9\" role=\"tab\" aria-controls=\"ha-accordion__item-content-1799\">\n                                                    <span class=\"ha-accordion__item-icon ha-accordion__icon\" aria-hidden=\"true\">\n                                                                    <span class=\"ha-accordion__icon--closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n                                                                                                    <span class=\"ha-accordion__icon--opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n                                                            <\/span>\n                                                <div class=\"ha-accordion__item-title-inner\">\n                                                        <span class=\"ha-accordion__item-title-text\">Was ist eine WAF (Web Application Firewall)?<\/span>\n                        <\/div>\n                    <\/div>\n                    <div id=\"ha-accordion__item-content-1799\" class=\"ha-accordion__item-content\" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"ha-accordion__item-title-1799\">\n                        <p>Eine WAF oder Web Application Firewall ist ein Sicherheitsger\u00e4t, das speziell daf\u00fcr entwickelt wurde, Bedrohungen auf der Anwendungsschicht, d.h. Layer7, zu entsch\u00e4rfen. Genauer gesagt, ist eine Web Application Firewall f\u00fcr die Arbeit mit HTTP- und HTTPS-Protokollen ausgelegt. Sie arbeiten in Verbindung mit einer Standard-Netzwerk-Firewall, die normalerweise Ports blockiert. Damit eine Anwendung einen \u00f6ffentlichen Dienst anbieten kann, m\u00fcssen bestimmte Ports (z. B. 80 und 443 f\u00fcr eine typische HTTP\/HTTPS-Web-App) offen sein. Hacker nutzen diese offenen Ports aus, was die Notwendigkeit einer zus\u00e4tzlichen, neuen Schutzschicht offenbart. An dieser Stelle kommt eine Application Firewall oder WAF ins Spiel. Eine Web Application Firewall pr\u00fcft die HTTP-Anfragen und -Antworten, um festzustellen, ob sie g\u00fcltig sind oder nicht. Einige Anfragen k\u00f6nnen f\u00fcr eine Site \/ Seite g\u00fcltig sein, f\u00fcr eine andere jedoch nicht, so dass in vielen F\u00e4llen die Application Firewalls mehr Konfiguration ben\u00f6tigen. PCI DSS verlangt von einer Application Firewall, dass sie einige Standardbedrohungen blockiert, entsprechend den von OWASP ver\u00f6ffentlichten Top-10-Bedrohungen.<\/p><\/p>\n                    <\/div>\n                <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FAQ Lassen Sie uns technisch werden Kostenlose Testversion herunterladen UNTERST\u00dcTZUNG KOSTENLOSES PROBLEM KONTAKT Glossar und FAQ zur Terminologie des Lastausgleichs Die Load-Balancing-Technologie hat sich in den letzten Jahren erheblich weiterentwickelt, so dass die Terminologie im Zusammenhang mit Application Delivery inzwischen recht verwirrend geworden ist. Angesichts der vielen Akronyme und des Fachjargons f\u00fchlt man sich leicht [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"parent":21216,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-21254","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FAQ&#039;s - Edgenexus Load balancer Anwendungssicherheit FAQ und Begriffe<\/title>\n<meta name=\"description\" content=\"Load Balancer FAQ und Terminologie - Was ist ein Load Balancer? Was sind die wichtigsten Begriffe und Definitionen?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/\",\"url\":\"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/\",\"name\":\"FAQ's - Edgenexus Load balancer Anwendungssicherheit FAQ und Begriffe\",\"isPartOf\":{\"@id\":\"https:\/\/www.edgenexus.io\/zh-hans\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.edgenexus.io\/wp-content\/uploads\/2021\/03\/edgenexus-tbd-faqAsset-1-768x492.png\",\"datePublished\":\"2021-06-04T10:53:38+00:00\",\"dateModified\":\"2022-07-07T14:44:15+00:00\",\"description\":\"Load Balancer FAQ und Terminologie - Was ist ein Load Balancer? Was sind die wichtigsten Begriffe und Definitionen?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/#primaryimage\",\"url\":\"https:\/\/www.edgenexus.io\/wp-content\/uploads\/2021\/03\/edgenexus-tbd-faqAsset-1-768x492.png\",\"contentUrl\":\"https:\/\/www.edgenexus.io\/wp-content\/uploads\/2021\/03\/edgenexus-tbd-faqAsset-1-768x492.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.edgenexus.io\/de\/edgenexus-load-balancing-adc-waf-und-gslb\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ressourcen\",\"item\":\"https:\/\/www.edgenexus.io\/de\/ressourcen\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Load Balancer FAQ und Terminologie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.edgenexus.io\/zh-hans\/#website\",\"url\":\"https:\/\/www.edgenexus.io\/zh-hans\/\",\"name\":\"Edgenexus load balancers and Application Security\",\"description\":\"Edgenexus Load Balancers, ADC and Web application Firewalls (WAF)\",\"publisher\":{\"@id\":\"https:\/\/www.edgenexus.io\/zh-hans\/#organization\"},\"alternateName\":\"Load balancers and Web application firewall\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.edgenexus.io\/zh-hans\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.edgenexus.io\/zh-hans\/#organization\",\"name\":\"Edgenexus\",\"url\":\"https:\/\/www.edgenexus.io\/zh-hans\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.edgenexus.io\/zh-hans\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.edgenexus.io\/wp-content\/uploads\/2023\/09\/edgenexus-adc-sq-transparentAsset-7.png\",\"contentUrl\":\"https:\/\/www.edgenexus.io\/wp-content\/uploads\/2023\/09\/edgenexus-adc-sq-transparentAsset-7.png\",\"width\":903,\"height\":921,\"caption\":\"Edgenexus\"},\"image\":{\"@id\":\"https:\/\/www.edgenexus.io\/zh-hans\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/edgenexusio\",\"https:\/\/x.com\/edgenexusio\",\"https:\/\/www.linkedin.com\/company\/edgenexus\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FAQ's - Edgenexus Load balancer Anwendungssicherheit FAQ und Begriffe","description":"Load Balancer FAQ und Terminologie - Was ist ein Load Balancer? Was sind die wichtigsten Begriffe und Definitionen?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/","url":"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/","name":"FAQ's - Edgenexus Load balancer Anwendungssicherheit FAQ und Begriffe","isPartOf":{"@id":"https:\/\/www.edgenexus.io\/zh-hans\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/#primaryimage"},"image":{"@id":"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.edgenexus.io\/wp-content\/uploads\/2021\/03\/edgenexus-tbd-faqAsset-1-768x492.png","datePublished":"2021-06-04T10:53:38+00:00","dateModified":"2022-07-07T14:44:15+00:00","description":"Load Balancer FAQ und Terminologie - Was ist ein Load Balancer? Was sind die wichtigsten Begriffe und Definitionen?","breadcrumb":{"@id":"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/#primaryimage","url":"https:\/\/www.edgenexus.io\/wp-content\/uploads\/2021\/03\/edgenexus-tbd-faqAsset-1-768x492.png","contentUrl":"https:\/\/www.edgenexus.io\/wp-content\/uploads\/2021\/03\/edgenexus-tbd-faqAsset-1-768x492.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.edgenexus.io\/de\/ressourcen\/load-balancer-faq-und-terminologie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.edgenexus.io\/de\/edgenexus-load-balancing-adc-waf-und-gslb\/"},{"@type":"ListItem","position":2,"name":"Ressourcen","item":"https:\/\/www.edgenexus.io\/de\/ressourcen\/"},{"@type":"ListItem","position":3,"name":"Load Balancer FAQ und Terminologie"}]},{"@type":"WebSite","@id":"https:\/\/www.edgenexus.io\/zh-hans\/#website","url":"https:\/\/www.edgenexus.io\/zh-hans\/","name":"Edgenexus load balancers and Application Security","description":"Edgenexus Load Balancers, ADC and Web application Firewalls (WAF)","publisher":{"@id":"https:\/\/www.edgenexus.io\/zh-hans\/#organization"},"alternateName":"Load balancers and Web application firewall","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.edgenexus.io\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.edgenexus.io\/zh-hans\/#organization","name":"Edgenexus","url":"https:\/\/www.edgenexus.io\/zh-hans\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.edgenexus.io\/zh-hans\/#\/schema\/logo\/image\/","url":"https:\/\/www.edgenexus.io\/wp-content\/uploads\/2023\/09\/edgenexus-adc-sq-transparentAsset-7.png","contentUrl":"https:\/\/www.edgenexus.io\/wp-content\/uploads\/2023\/09\/edgenexus-adc-sq-transparentAsset-7.png","width":903,"height":921,"caption":"Edgenexus"},"image":{"@id":"https:\/\/www.edgenexus.io\/zh-hans\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/edgenexusio","https:\/\/x.com\/edgenexusio","https:\/\/www.linkedin.com\/company\/edgenexus\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.edgenexus.io\/de\/wp-json\/wp\/v2\/pages\/21254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.edgenexus.io\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.edgenexus.io\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.edgenexus.io\/de\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.edgenexus.io\/de\/wp-json\/wp\/v2\/comments?post=21254"}],"version-history":[{"count":0,"href":"https:\/\/www.edgenexus.io\/de\/wp-json\/wp\/v2\/pages\/21254\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.edgenexus.io\/de\/wp-json\/wp\/v2\/pages\/21216"}],"wp:attachment":[{"href":"https:\/\/www.edgenexus.io\/de\/wp-json\/wp\/v2\/media?parent=21254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}